{"id":180,"count":1,"description":"","link":"https:\/\/deliciaspersas.com\/en\/brand\/zine\/","name":"Zine","slug":"zine","taxonomy":"pwb-brand","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Zine archivos - Delicias Persas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/deliciaspersas.com\/en\/brand\/zine\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zine archivos - Delicias Persas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/deliciaspersas.com\/en\/brand\/zine\/\" \/>\n<meta property=\"og:site_name\" content=\"Delicias Persas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/deliciaspersas.com\/en\/brand\/zine\/\",\"url\":\"https:\/\/deliciaspersas.com\/en\/brand\/zine\/\",\"name\":\"Zine archivos - Delicias Persas\",\"isPartOf\":{\"@id\":\"https:\/\/deliciaspersas.com\/en\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/deliciaspersas.com\/en\/brand\/zine\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/deliciaspersas.com\/en\/brand\/zine\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/deliciaspersas.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zine\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/deliciaspersas.com\/en\/#website\",\"url\":\"https:\/\/deliciaspersas.com\/en\/\",\"name\":\"Delicias Persas\",\"description\":\"Gastronom&iacute;a persa al alcance de tus manos\",\"publisher\":{\"@id\":\"https:\/\/deliciaspersas.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/deliciaspersas.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/deliciaspersas.com\/en\/#organization\",\"name\":\"Delicias Persas\",\"url\":\"https:\/\/deliciaspersas.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/deliciaspersas.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/deliciaspersas.com\/wp-content\/uploads\/2020\/07\/logo-2020.png\",\"contentUrl\":\"https:\/\/deliciaspersas.com\/wp-content\/uploads\/2020\/07\/logo-2020.png\",\"width\":520,\"height\":490,\"caption\":\"Delicias Persas\"},\"image\":{\"@id\":\"https:\/\/deliciaspersas.com\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Deliciaspersas\",\"https:\/\/www.instagram.com\/delicias_persas\/\",\"https:\/\/www.linkedin.com\/delicias-persas\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zine archivos - Delicias Persas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/deliciaspersas.com\/en\/brand\/zine\/","og_locale":"en_US","og_type":"article","og_title":"Zine archivos - Delicias Persas","og_url":"https:\/\/deliciaspersas.com\/en\/brand\/zine\/","og_site_name":"Delicias Persas","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/deliciaspersas.com\/en\/brand\/zine\/","url":"https:\/\/deliciaspersas.com\/en\/brand\/zine\/","name":"Zine archivos - Delicias Persas","isPartOf":{"@id":"https:\/\/deliciaspersas.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/deliciaspersas.com\/en\/brand\/zine\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/deliciaspersas.com\/en\/brand\/zine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/deliciaspersas.com\/en\/"},{"@type":"ListItem","position":2,"name":"Zine"}]},{"@type":"WebSite","@id":"https:\/\/deliciaspersas.com\/en\/#website","url":"https:\/\/deliciaspersas.com\/en\/","name":"Delicias Persas","description":"Gastronom&iacute;a persa al alcance de tus manos","publisher":{"@id":"https:\/\/deliciaspersas.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/deliciaspersas.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/deliciaspersas.com\/en\/#organization","name":"Delicias Persas","url":"https:\/\/deliciaspersas.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/deliciaspersas.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/deliciaspersas.com\/wp-content\/uploads\/2020\/07\/logo-2020.png","contentUrl":"https:\/\/deliciaspersas.com\/wp-content\/uploads\/2020\/07\/logo-2020.png","width":520,"height":490,"caption":"Delicias Persas"},"image":{"@id":"https:\/\/deliciaspersas.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deliciaspersas","https:\/\/www.instagram.com\/delicias_persas\/","https:\/\/www.linkedin.com\/delicias-persas"]}]}},"_links":{"self":[{"href":"https:\/\/deliciaspersas.com\/en\/wp-json\/wp\/v2\/pwb-brand\/180"}],"collection":[{"href":"https:\/\/deliciaspersas.com\/en\/wp-json\/wp\/v2\/pwb-brand"}],"about":[{"href":"https:\/\/deliciaspersas.com\/en\/wp-json\/wp\/v2\/taxonomies\/pwb-brand"}],"wp:post_type":[{"href":"https:\/\/deliciaspersas.com\/en\/wp-json\/wp\/v2\/product?pwb-brand=180"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}