{"id":1618,"count":1,"description":"","link":"https:\/\/deliciaspersas.com\/fa\/categoria-producto\/groceries\/","name":"Groceries","slug":"groceries","taxonomy":"product_cat","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Groceries archivos - Delicias Persas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/deliciaspersas.com\/fa\/categoria-producto\/groceries\/\" \/>\n<meta property=\"og:locale\" content=\"fa_IR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Groceries archivos - Delicias Persas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/deliciaspersas.com\/fa\/categoria-producto\/groceries\/\" \/>\n<meta property=\"og:site_name\" content=\"Delicias Persas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/deliciaspersas.com\/fa\/categoria-producto\/groceries\/\",\"url\":\"https:\/\/deliciaspersas.com\/fa\/categoria-producto\/groceries\/\",\"name\":\"Groceries archivos - Delicias Persas\",\"isPartOf\":{\"@id\":\"https:\/\/deliciaspersas.com\/fa\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/deliciaspersas.com\/fa\/categoria-producto\/groceries\/#breadcrumb\"},\"inLanguage\":\"fa-IR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/deliciaspersas.com\/fa\/categoria-producto\/groceries\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/deliciaspersas.com\/fa\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Groceries\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/deliciaspersas.com\/fa\/#website\",\"url\":\"https:\/\/deliciaspersas.com\/fa\/\",\"name\":\"Delicias Persas\",\"description\":\"Gastronom&iacute;a persa al alcance de tus manos\",\"publisher\":{\"@id\":\"https:\/\/deliciaspersas.com\/fa\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/deliciaspersas.com\/fa\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fa-IR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/deliciaspersas.com\/fa\/#organization\",\"name\":\"Delicias Persas\",\"url\":\"https:\/\/deliciaspersas.com\/fa\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fa-IR\",\"@id\":\"https:\/\/deliciaspersas.com\/fa\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/deliciaspersas.com\/wp-content\/uploads\/2020\/07\/logo-2020.png\",\"contentUrl\":\"https:\/\/deliciaspersas.com\/wp-content\/uploads\/2020\/07\/logo-2020.png\",\"width\":520,\"height\":490,\"caption\":\"Delicias Persas\"},\"image\":{\"@id\":\"https:\/\/deliciaspersas.com\/fa\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Deliciaspersas\",\"https:\/\/www.instagram.com\/delicias_persas\/\",\"https:\/\/www.linkedin.com\/delicias-persas\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Groceries archivos - Delicias Persas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/deliciaspersas.com\/fa\/categoria-producto\/groceries\/","og_locale":"fa_IR","og_type":"article","og_title":"Groceries archivos - Delicias Persas","og_url":"https:\/\/deliciaspersas.com\/fa\/categoria-producto\/groceries\/","og_site_name":"Delicias Persas","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/deliciaspersas.com\/fa\/categoria-producto\/groceries\/","url":"https:\/\/deliciaspersas.com\/fa\/categoria-producto\/groceries\/","name":"Groceries archivos - Delicias Persas","isPartOf":{"@id":"https:\/\/deliciaspersas.com\/fa\/#website"},"breadcrumb":{"@id":"https:\/\/deliciaspersas.com\/fa\/categoria-producto\/groceries\/#breadcrumb"},"inLanguage":"fa-IR"},{"@type":"BreadcrumbList","@id":"https:\/\/deliciaspersas.com\/fa\/categoria-producto\/groceries\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/deliciaspersas.com\/fa\/"},{"@type":"ListItem","position":2,"name":"Groceries"}]},{"@type":"WebSite","@id":"https:\/\/deliciaspersas.com\/fa\/#website","url":"https:\/\/deliciaspersas.com\/fa\/","name":"Delicias Persas","description":"Gastronom&iacute;a persa al alcance de tus manos","publisher":{"@id":"https:\/\/deliciaspersas.com\/fa\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/deliciaspersas.com\/fa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fa-IR"},{"@type":"Organization","@id":"https:\/\/deliciaspersas.com\/fa\/#organization","name":"Delicias Persas","url":"https:\/\/deliciaspersas.com\/fa\/","logo":{"@type":"ImageObject","inLanguage":"fa-IR","@id":"https:\/\/deliciaspersas.com\/fa\/#\/schema\/logo\/image\/","url":"https:\/\/deliciaspersas.com\/wp-content\/uploads\/2020\/07\/logo-2020.png","contentUrl":"https:\/\/deliciaspersas.com\/wp-content\/uploads\/2020\/07\/logo-2020.png","width":520,"height":490,"caption":"Delicias Persas"},"image":{"@id":"https:\/\/deliciaspersas.com\/fa\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Deliciaspersas","https:\/\/www.instagram.com\/delicias_persas\/","https:\/\/www.linkedin.com\/delicias-persas"]}]}},"_links":{"self":[{"href":"https:\/\/deliciaspersas.com\/fa\/wp-json\/wp\/v2\/product_cat\/1618"}],"collection":[{"href":"https:\/\/deliciaspersas.com\/fa\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/deliciaspersas.com\/fa\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/deliciaspersas.com\/fa\/wp-json\/wp\/v2\/product?product_cat=1618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}